{"id":404,"date":"2013-09-06T17:46:53","date_gmt":"2013-09-06T15:46:53","guid":{"rendered":"http:\/\/dogdeliver.com\/blog\/?p=404"},"modified":"2017-07-04T11:29:33","modified_gmt":"2017-07-04T09:29:33","slug":"test-di-intelligenza-per-cani","status":"publish","type":"post","link":"https:\/\/www.dogdeliver.com\/blog\/2013\/09\/06\/test-di-intelligenza-per-cani\/","title":{"rendered":"Test di intelligenza per cani"},"content":{"rendered":"<p style=\"text-align: justify;\">Ciao a tutti!<\/p>\n<p style=\"text-align: justify;\">Come promesso vi riporto alcuni test che si possono fare per calcolare la nostra (dei vostri amati quadrupedi) intelligenza. Li ha disegnati il Dr. Stanley Coren di cui vi ho scritto <a title=\"L'intelligenza dei cani\" href=\"http:\/\/dogdeliver.com\/blog\/it\/2013\/09\/06\/lintelligenza-dei-cani\/\" target=\"_blank\" rel=\"noopener\">poco fa.<\/a><\/p>\n<p style=\"text-align: justify;\">Hanno alcune regole che vanno rispettate:<\/p>\n<p style=\"text-align: justify;\">1. Farli con il proprio cane, che deve avere almeno un anno e deve vivere con voi da almeno 3 mesi.<\/p>\n<p style=\"text-align: justify;\">2. Per noi deve essere un gioco (test = gioco), se no si rischia che ci stanchiamo e quindi facciamo male solo per quello, oppure che soffriamo e non va bene.<\/p>\n<p style=\"text-align: justify;\">3. Mantenete la calma sia che pensiate di avere di fronte il nuovo Leonardo da Vinci a quattro zampe, sia che siate delusissimi perch\u00e8 non capiamo niente.<\/p>\n<p style=\"text-align: justify;\">4. Visto che i premi sono in cibo, meglio non farli troppo ravvicinati se no perdiamo interesse e facciamo male solo per quello.<\/p>\n<p style=\"text-align: justify;\">Dotatevi di carta e penna per segnare i punteggi che servono per i risultati finali.<\/p>\n<p style=\"text-align: justify;\"><strong>Test numero 1, per valutare la nostra capacit\u00e0 di risolvere problemi<\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>Materiale necessario<\/strong>: un barattolo vuoto, uno snackino che il cane apprezza molto, un cronometro.<\/p>\n<p style=\"text-align: justify;\"><strong>a<\/strong>. Far sedere il cane e tenerlo fermo <strong>b<\/strong>. Mostrargli lo snack e farglielo odorare <strong>3<\/strong>. Quando il cane \u00e8 ben attento, poggiare lo snack per terra a circa due metri di distanza e coprirlo con il barattolo <strong>4<\/strong>. Accendere il cronometro e invitare il cane a trovare il cibo<\/p>\n<p style=\"text-align: justify;\"><strong>Punteggio:<\/strong><\/p>\n<p style=\"text-align: justify;\">5 punti se il cane che trova il cibo e abbatte il barattolo in 5 secondi o meno<\/p>\n<p style=\"text-align: justify;\">4 punti se il cane trova il cibo e abbatte il barattolo in 5-15 secondi<\/p>\n<p style=\"text-align: justify;\">3 punti se il cane trova il cibo e abbatte il barattolo in 15-30 secondi<\/p>\n<p style=\"text-align: justify;\">2 punti se il cane trova il cibo e abbatte il barattolo in 30-60 secondi<\/p>\n<p style=\"text-align: justify;\">1 punto se il cane si avvicina al barattolo e lo odora ma non riesce a recuperare lo snack<\/p>\n<p style=\"text-align: justify;\"><strong>Test numero 2, per valutare la nostra capacit\u00e0 di risolvere problemi<\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>Materiale necessario<\/strong>: un asciugamano da doccia, un cronometro (e uno snack per premiarlo se fa bene).<\/p>\n<p style=\"text-align: justify;\">E&#8217; necessario che il cane sia sveglio e attivo<\/p>\n<p style=\"text-align: justify;\"><strong>a<\/strong>. Fargli odorare l&#8217;asciugamano<strong> b<\/strong>. Con un movimento veloce coprirgli la testa e le spalle con l&#8217;asciugamano. <strong>c<\/strong> Far partire il cronometro e osservare in silenzio.<\/p>\n<p style=\"text-align: justify;\"><strong>Punteggio:<\/strong><\/p>\n<p style=\"text-align: justify;\">5 punti se il cane riesce a liberarsi in 5 secondi o meno<\/p>\n<p style=\"text-align: justify;\">4 punti se il cane riesce a liberarsi in 5-15 secondi<\/p>\n<p style=\"text-align: justify;\">3 punti se il cane riesce a liberarsi in 15-30 secondi<\/p>\n<p style=\"text-align: justify;\">2 punti se il cane riesce a liberarsi in 30-60 secondi<\/p>\n<p style=\"text-align: justify;\">1 punto se il cane riesce a liberarsi dopo 1 minuto<\/p>\n<p style=\"text-align: justify;\"><strong>Test numero 3, per valutare la nostra capacit\u00e0 di imparare le relazioni con gli umani<\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>a<\/strong>. Scegliere un momento in cui il cane \u00e8 seduto spontaneamente a circa 2 m di distanza da voi; <strong>b<\/strong>. Guardarlo intensamente in faccia e quando inizia a ricambiare lo sguardo, far passare tre secondi senza parlare e poi sorridere apertamente.<\/p>\n<p style=\"text-align: justify;\"><strong>Punteggio:<\/strong><\/p>\n<p style=\"text-align: justify;\">5 punti se il cane si alza e arriva scondinzolando<\/p>\n<p style=\"text-align: justify;\">4 punti se il cane si alza e fa un po&#8217; di strada ma non scodinzola<\/p>\n<p style=\"text-align: justify;\">3 punti se il cane si alza o si siede ma non si muove verso di voi<\/p>\n<p style=\"text-align: justify;\">2 punti se il cane si allontana<\/p>\n<p style=\"text-align: justify;\">1 punto se il cane non presta attenzione e non si accorge di nulla.<\/p>\n<p style=\"text-align: justify;\"><strong>Test numero 4, per vautare la capacit\u00e0 di risolvere problemi<\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>Materiale necessario<\/strong>: un asciugamano da mani, un biscotto per cani abbastanza grande, un cronometro.<\/p>\n<p style=\"text-align: justify;\"><strong>a<\/strong>. Sedetevi con il vostro cane e se non sta fermo avrete bisogno di qualcuno che lo tenga per il collare; <strong>b<\/strong>. Mostrate al cane il biscotto e lasciateglielo odorare <strong>c<\/strong>. Assicurandovi che il cane stia osservando attentamente, poggiate il biscotto per terra a circa 2m di distanza e, sempre mentre il cane guarda, coprite il biscotto con l&#8217;asciugamano. <strong>d<\/strong>. Fate partire il cronometro e invitate il cane a trovare il biscotto<\/p>\n<p style=\"text-align: justify;\"><strong>Punteggio:<\/strong><\/p>\n<p style=\"text-align: justify;\">5 punti se il cane che trova il biscotto in 15 secondi o meno<\/p>\n<p style=\"text-align: justify;\">4 punti se il cane trova il biscotto in 15-30 secondi<\/p>\n<p style=\"text-align: justify;\">3 punti se il cane trova il biscotto in 30-60 secondi<\/p>\n<p style=\"text-align: justify;\">2 punti se il cane prova a cercare il biscotto e poi si arrende<\/p>\n<p style=\"text-align: justify;\">1 punto se il cane non cerca nemmeno il biscotto<\/p>\n<p style=\"text-align: justify;\"><strong>Test numero 5, per valutare la capacit\u00e0 di risolvere problemi e trovare soluzioni<\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>Materiale necessario<\/strong>: un &#8220;tavolino&#8221; basso abbastanza da non pernettere al cane di metterci sotto la testa ma alto abbastanza da permettergli di arrivare sotto con la zampa; un biscottone per cani; un cronometro.<\/p>\n<p style=\"text-align: justify;\"><strong>a<\/strong>. mostrare al cane il biscottone e farglielo odorare; <strong>b<\/strong>. facendosi osservare dal cane, sistemare il biscotto sotto il tavolo ad una distanza a cui pu\u00f2 arrivare con la zampa; <strong>c<\/strong>. Far partire il cronometro e incoraggiarlo a recuperare il biscotto.<\/p>\n<p style=\"text-align: justify;\">Punteggio:<\/p>\n<p style=\"text-align: justify;\">5 punti se il cane usa la zampa per recuperare il biscotto e ci mette 1 minuto o meno<\/p>\n<p style=\"text-align: justify;\">4 punti se il cane usa la zampa per recuperare il biscotto e ci mette da 1 a 3 minuti<\/p>\n<p style=\"text-align: justify;\">3 punti se il cane usa solo il muso e non riesce a recuperare il biscotto oppure usa le zampe e dopo tre minuti non \u00e8 riuscito a prenderlo<\/p>\n<p style=\"text-align: justify;\">2 punti se il cane non usa le zampe, fa un paio di tentativi con il muso e poi lascia perdere<\/p>\n<p style=\"text-align: justify;\">1 punto se il cane dopo tre minuti non ha provato a prendere il biscotto<\/p>\n<p style=\"text-align: justify;\"><strong>Test numero 6, per valutare la comprensione del linguaggio<\/strong><\/p>\n<p style=\"text-align: justify;\">Il cane \u00e8 seduto comodamente a circa due metri da voi,\u00a0 e con la stessa voce con cui chiamate il suo nome, dite la parola &#8220;frigorifero&#8221;.<\/p>\n<p style=\"text-align: justify;\"><strong>Punteggio:<\/strong><\/p>\n<p style=\"text-align: justify;\">5 punti se il cane non risponde e mostra intenzione di muoversi solo dopo che lo chiamate per nome<\/p>\n<p style=\"text-align: justify;\">4 punti se il cane non viene la prima volta che chiamate il suo nome, ma alla seconda si alza e viene<\/p>\n<p style=\"text-align: justify;\">3 punti se il cane si mostra interessato e viene<\/p>\n<p style=\"text-align: justify;\">2 punti se il cane non viene, ma dicendo la parola &#8220;film&#8221; nello stesso tono viene<\/p>\n<p style=\"text-align: justify;\">1 punto se il cane non fa niente<\/p>\n<p style=\"text-align: justify;\"><strong>Risultati<\/strong><\/p>\n<p style=\"text-align: justify;\">25 punti e pi\u00f9: il cane \u00e8 effettivamente Leonardo da Vinci (= un genio)<\/p>\n<p style=\"text-align: justify;\">15-25 punti: cane intelligente<\/p>\n<p style=\"text-align: justify;\">5-15 punti: un tenerone, \u00e8 quello che conta<\/p>\n<p style=\"text-align: justify;\">meno di 5 punti: ehm ehm, w i padroni a cui ci si affida per tutto!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Test semi seri per avere una idea della capacit\u00e0 dei cani di risolvere i problemi<\/p>\n","protected":false},"author":10,"featured_media":406,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[797],"tags":[298,1049,1134,22,756,1135,564,357,603],"class_list":["post-404","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-educazione-cinofila","tag-cani","tag-capacita","tag-creativita","tag-educazione","tag-intelligenza","tag-inventiva","tag-problemi","tag-relazione","tag-umani"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"Alcuni esercizi che si possono fare per avere una idea di come i cani affrontano il mondo\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Oban\"\/>\n\t<meta name=\"google-site-verification\" content=\"d7unO9higxboxR16EmDWjP6HiEOgCVcAv5v7y-by9xM\" \/>\n\t<meta name=\"keywords\" content=\"cani,educazione,intelligenza,problemi,creativit\u00e0,capacit\u00e0,inventiva,relazione,umani\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.dogdeliver.com\/blog\/2013\/09\/06\/test-di-intelligenza-per-cani\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Test di intelligenza per cani | Dogdeliver","description":"Alcuni esercizi che si possono fare per avere una idea di come i cani affrontano il mondo","canonical_url":"https:\/\/www.dogdeliver.com\/blog\/2013\/09\/06\/test-di-intelligenza-per-cani\/","robots":"max-image-preview:large","keywords":"cani,educazione,intelligenza,problemi,creativit\u00e0,capacit\u00e0,inventiva,relazione,umani","webmasterTools":{"google-site-verification":"d7unO9higxboxR16EmDWjP6HiEOgCVcAv5v7y-by9xM","miscellaneous":""},"schema":null},"aioseo_meta_data":{"post_id":"404","title":null,"description":"Alcuni esercizi che si possono fare per avere una idea di come i cani affrontano il mondo","keywords":[{"label":"cani","value":"cani"},{"label":"educazione","value":"educazione"},{"label":"intelligenza","value":"intelligenza"},{"label":"problemi","value":"problemi"},{"label":"creativit\u00e0","value":"creativit\u00e0"},{"label":"capacit\u00e0","value":"capacit\u00e0"},{"label":"inventiva","value":"inventiva"},{"label":"relazione","value":"relazione"},{"label":"umani","value":"umani"}],"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"location":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2020-12-21 05:33:16","updated":"2022-09-14 17:23:48","seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.dogdeliver.com\/blog\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">\u203a<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.dogdeliver.com\/blog\/category\/educazione-cinofila\/\" title=\"Educazione Cinofila\">Educazione Cinofila<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">\u203a<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tTest di intelligenza per cani\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/www.dogdeliver.com\/blog"},{"label":"Educazione Cinofila","link":"https:\/\/www.dogdeliver.com\/blog\/category\/educazione-cinofila\/"},{"label":"Test di intelligenza per cani","link":"https:\/\/www.dogdeliver.com\/blog\/2013\/09\/06\/test-di-intelligenza-per-cani\/"}],"_links":{"self":[{"href":"https:\/\/www.dogdeliver.com\/blog\/wp-json\/wp\/v2\/posts\/404","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.dogdeliver.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.dogdeliver.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.dogdeliver.com\/blog\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/www.dogdeliver.com\/blog\/wp-json\/wp\/v2\/comments?post=404"}],"version-history":[{"count":0,"href":"https:\/\/www.dogdeliver.com\/blog\/wp-json\/wp\/v2\/posts\/404\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.dogdeliver.com\/blog\/wp-json\/wp\/v2\/media\/406"}],"wp:attachment":[{"href":"https:\/\/www.dogdeliver.com\/blog\/wp-json\/wp\/v2\/media?parent=404"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.dogdeliver.com\/blog\/wp-json\/wp\/v2\/categories?post=404"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.dogdeliver.com\/blog\/wp-json\/wp\/v2\/tags?post=404"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}