{"id":2216,"date":"2014-10-24T16:57:19","date_gmt":"2014-10-24T14:57:19","guid":{"rendered":"http:\/\/dogdeliver.com\/blog\/?p=2216"},"modified":"2016-12-14T10:35:49","modified_gmt":"2016-12-14T09:35:49","slug":"i-test-di-nina-e-oban-pate-bio-nologo","status":"publish","type":"post","link":"https:\/\/www.dogdeliver.com\/blog\/2014\/10\/24\/i-test-di-nina-e-oban-pate-bio-nologo\/","title":{"rendered":"I test di Nina e Oban: Pat\u00e8 Bio nologo"},"content":{"rendered":"<p>Ciao a tutti!<\/p>\n<p>Come va? Io sono un fiore. Oggi c&#8217;\u00e8 un sole fantastico, ho giocato pi\u00f9 di due ore a palla al giardino, e ho appena finito di mangiare squisitezze per cui sono proprio di ottimissimo umore.<\/p>\n<p>Ora vi racconto una di quelle cose meravigliose che ho mangiato poco fa, il <strong>pat\u00e8 bio no logo<\/strong> che abbiamo inviato nella<strong> box di ottobre<\/strong>.<\/p>\n<p>Ormai vi ho raccontato un bel po&#8217; di volte che io di pancia sono messo non proprio benissimo (ho una colite autoimmune) per cui posso mangiare quasi solo croccantini super speciali per chi ha la colite come me e sulle cose sfiziose devo stare proprio attento. Non che non mi piacciano, eh, \u00e8 solo che se subito dopo aver mangiato devo volare a pigolare dalla padrona e sperare che capisca che mi deve portare fuori non \u00e8 il massimo, diciamo che toglie un po&#8217; di fascino al pasto luculliano.<\/p>\n<p>Sento che i miei amici hanno da mangiare quando tornano dal giardino la mattina e poi la sera sempre agli stessi orari. Io no, i miei mi danno da mangiare quando si ricordano e a volte ho cos\u00ec tanta fame che devo ricordarglielo io. E&#8217; facilissimo, vado dove lavora la padrona, pigolo forte cos\u00ec lei si alza, mi faccio seguire fino alla cucina, alzo il muso verso la ciotola e lei finalmente ha imparato che tutta questa storia vuol dire che voglio mangiare per cui me lo da.<\/p>\n<p>Ecco anche oggi mi sono stra dilungato. Scusate! Stavo dicendo il <strong>pat\u00e8 bio no logo, semplicemente divino<\/strong>.<\/p>\n<p>Siamo tornati dopo un bel po&#8217; di tempo al giardino, per cui ero bello stanco, la padrona si stava facendo le polpette e il profumo mi ha fatto venire un languorino che non vi posso dire per cui piii, piiii, mi sono messo a pigolare, messaggio di fame inviato! E lei ha fatto una cosa fantastica: ha preso delle scatoline nuove, le ha aperte, me le ha fatte odorare, mi ha fatto sedere, e ha mischiato il dentro ai miei croccantini. Mi ha dato l&#8217;ok e io che da un po&#8217; sentivo un profumo pazzesco mi sono lanciato sulla ciotola come un sol cane.<\/p>\n<p><strong>Apriti cielo<\/strong>. Il <strong>palato \u00e8 stato travolto da un mare di gusto<\/strong>, era il <strong>pat\u00e8 bio no logo<\/strong>. Posso dire che al suo confronto le polpette dei miei umani sono niente? Mi sono sono dimenticato che le stavano preparando!<\/p>\n<p>Il motivo per cui lo abbiamo scelto \u00e8 che <strong>il pat\u00e8 \u00e8 molto speciale<\/strong>, <strong>\u00e8 al 100% biologico,<\/strong> prodotto secondo severe norme, \u00e8 super squisito &#8211; ma solo perch\u00e8 \u00e8 proprio buono perch\u00e8 nel biologico non sono permesse sostanze appetizzanti &#8211; sano, nutriente, e digeribile. <strong>Favvissimo!!!!<\/strong><\/p>\n<div id='gallery-1' class='gallery galleryid-2216 gallery-columns-4 gallery-size-thumbnail'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.dogdeliver.com\/blog\/wp-content\/uploads\/2014\/10\/DSC_0012.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.dogdeliver.com\/blog\/wp-content\/uploads\/2014\/10\/DSC_0012-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.dogdeliver.com\/blog\/wp-content\/uploads\/2014\/10\/DSC_0013.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.dogdeliver.com\/blog\/wp-content\/uploads\/2014\/10\/DSC_0013-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.dogdeliver.com\/blog\/wp-content\/uploads\/2014\/10\/DSC_0014.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.dogdeliver.com\/blog\/wp-content\/uploads\/2014\/10\/DSC_0014-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.dogdeliver.com\/blog\/wp-content\/uploads\/2014\/10\/DSC_0015.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.dogdeliver.com\/blog\/wp-content\/uploads\/2014\/10\/DSC_0015-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" \/><\/a>\n\t\t\t<\/div><\/figure>\n\t\t<\/div>\n\n<p>Tanti saluti dal Vostro Obanino, blogger blue merle dalla coda corta<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ciao a tutti! Come va? Io sono un fiore. Oggi c&#8217;\u00e8 un sole fantastico, ho giocato pi\u00f9 di due ore a palla al giardino, e ho appena finito di mangiare squisitezze per cui sono proprio di ottimissimo umore. Ora vi&#8230;<\/p>\n","protected":false},"author":10,"featured_media":2217,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[797],"tags":[49,298,50,299],"class_list":["post-2216","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-educazione-cinofila","tag-alimentazione","tag-cani","tag-dogdeliver-2","tag-salute"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Oban\"\/>\n\t<meta name=\"google-site-verification\" content=\"d7unO9higxboxR16EmDWjP6HiEOgCVcAv5v7y-by9xM\" \/>\n\t<meta name=\"keywords\" content=\"alimentazione,cani,dogdeliver,salute\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.dogdeliver.com\/blog\/2014\/10\/24\/i-test-di-nina-e-oban-pate-bio-nologo\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"I test di Nina e Oban: Pat\u00e8 Bio nologo | Dogdeliver","description":"","canonical_url":"https:\/\/www.dogdeliver.com\/blog\/2014\/10\/24\/i-test-di-nina-e-oban-pate-bio-nologo\/","robots":"max-image-preview:large","keywords":"alimentazione,cani,dogdeliver,salute","webmasterTools":{"google-site-verification":"d7unO9higxboxR16EmDWjP6HiEOgCVcAv5v7y-by9xM","miscellaneous":""},"schema":null},"aioseo_meta_data":{"post_id":"2216","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[],"defaultGraph":"","defaultPostTypeGraph":""},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"location":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2020-12-21 05:34:52","updated":"2022-09-15 11:03:48","seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.dogdeliver.com\/blog\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">\u203a<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.dogdeliver.com\/blog\/category\/educazione-cinofila\/\" title=\"Educazione Cinofila\">Educazione Cinofila<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">\u203a<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tI test di Nina e Oban: Pat\u00e8 Bio nologo\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/www.dogdeliver.com\/blog"},{"label":"Educazione Cinofila","link":"https:\/\/www.dogdeliver.com\/blog\/category\/educazione-cinofila\/"},{"label":"I test di Nina e Oban: Pat\u00e8 Bio nologo","link":"https:\/\/www.dogdeliver.com\/blog\/2014\/10\/24\/i-test-di-nina-e-oban-pate-bio-nologo\/"}],"_links":{"self":[{"href":"https:\/\/www.dogdeliver.com\/blog\/wp-json\/wp\/v2\/posts\/2216","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.dogdeliver.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.dogdeliver.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.dogdeliver.com\/blog\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/www.dogdeliver.com\/blog\/wp-json\/wp\/v2\/comments?post=2216"}],"version-history":[{"count":0,"href":"https:\/\/www.dogdeliver.com\/blog\/wp-json\/wp\/v2\/posts\/2216\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.dogdeliver.com\/blog\/wp-json\/wp\/v2\/media\/2217"}],"wp:attachment":[{"href":"https:\/\/www.dogdeliver.com\/blog\/wp-json\/wp\/v2\/media?parent=2216"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.dogdeliver.com\/blog\/wp-json\/wp\/v2\/categories?post=2216"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.dogdeliver.com\/blog\/wp-json\/wp\/v2\/tags?post=2216"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}